{"id":1522,"date":"2012-12-02T00:22:37","date_gmt":"2012-12-01T23:22:37","guid":{"rendered":"http:\/\/www.uscars.biz\/uscars.wordpress\/?page_id=1522"},"modified":"2025-06-07T19:04:18","modified_gmt":"2025-06-07T17:04:18","slug":"historique-cherokee-xj","status":"publish","type":"page","link":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/","title":{"rendered":"Historique du Cherokee XJ"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1643 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1984\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg\" alt=\"\" width=\"320\" height=\"224\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg 320w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984-300x210.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1642 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1984_4\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984_4.jpg\" alt=\"\" width=\"208\" height=\"112\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1660 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1984_3+2\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984_3+2.png\" alt=\"\" width=\"320\" height=\"112\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984_3+2.png 320w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984_3+2-300x105.png 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ayant acquis la majorit\u00e9 du capital d&rsquo;American Motors \u00e0 la fin des ann\u00e9es 1970, Renault dirige l&rsquo;\u00e9tude d&rsquo;un tout nouveau mod\u00e8le moins volumineux et plus moderne. C&rsquo;est ainsi qu&rsquo;en 1984, au terme d&rsquo;un projet de 250 millions de Dollars, Jeep r\u00e9volutionne le segment des v\u00e9hicules \u00ab\u00a0sport utilitaire\u00a0\u00bb \u00e0 quatre roues motrices en pr\u00e9sentant la nouvelle gamme XJ compos\u00e9e du Cherokee et du Wagoneer.<\/p>\n<p>Par rapport au Wagoneer pr\u00e9sent\u00e9 en 1962, les XJ sont plus courts de 50 centim\u00e8tres, plus \u00e9troits de 15 centim\u00e8tres, moins hauts de 10 centim\u00e8tres et moins lourds de 500 kilos. Le Wagoneer, uniquement disponible en quatre portes, reprend les \u00e9l\u00e9ments du Cherokee \u00e0 la calandre avec quatre phares pr\u00e8s. Deux niveaux de finition sont disponibles en plus de la finition de base. La version Pioneer offre la moquette, une instrumentation plus fournie, une console centrale et un essuie-glace arri\u00e8re tandis que la sportive version Chief re\u00e7oit une peinture sp\u00e9cifique sombre, des placages int\u00e9rieurs en bois et des pneus avec inscriptions blanches.<\/p>\n<p>Le Cherokee utilise un moteur quatre cylindres essence avec carburateur simple corps de 2,5 litres d\u00e9veloppant 105 chevaux ou en option un moteur six cylindres en V essence avec carburateur double corps de 2,8 litres d\u00e9veloppant 115 chevaux d&rsquo;origine Chevrolet (General Motors). Seule une bo\u00eete de vitesses manuelle \u00e0 quatre rapports est disponible avec le moteur quatre cylindres essence tandis que la motorisation sup\u00e9rieure peut recevoir la m\u00eame bo\u00eete manuelle, une bo\u00eete manuelle japonaise \u00e0 cinq rapports ou une bo\u00eete automatique \u00e0 trois rapports. Deux transmissions sont commercialis\u00e9es. La premi\u00e8re, baptis\u00e9e \u00ab\u00a0Command Trac\u00a0\u00bb, est une transmission 4&#215;4 enclenchable tandis que la deuxi\u00e8me, baptis\u00e9e \u00ab\u00a0Selec Trac\u00a0\u00bb, est une transmission 4&#215;4 permanente. La suspension avant \u00ab\u00a0Quadra Link\u00a0\u00bb, compos\u00e9e d&rsquo;un essieu rigide suspendu par quatre bras et deux ressorts h\u00e9lico\u00efdaux, donne au Cherokee de tr\u00e8s bonnes aptitudes au tout-terrain. Tr\u00e8s bien accueilli par la presse et le public, 78.000 exemplaires sont vendus la premi\u00e8re ann\u00e9e.<\/p>\n<p>La gamme est compl\u00e9t\u00e9e en 1985 par la finition Laredo. Plac\u00e9e au dessus de la finition Pioneer, elle b\u00e9n\u00e9ficie de mat\u00e9riaux int\u00e9rieurs plus luxueux, de filets lat\u00e9raux, de jantes en alliage et d&rsquo;une calandre chrom\u00e9e. Tous les mod\u00e8les re\u00e7oivent des appui-t\u00eate \u00e0 l&rsquo;avant et des poign\u00e9es de maintien pour chacun des passagers. Pour ceux qui n&rsquo;ont pas l&rsquo;utilit\u00e9 d&rsquo;une transmission 4&#215;4, le Cherokee est propos\u00e9 en simple propulsion. De nouvelles options font leur apparition comme le verrouillage centralis\u00e9 et le moteur quatre cylindres Turbo Diesel Renault de 2068 cm3 d\u00e9veloppant 88 chevaux.<\/p>\n<p>C&rsquo;est en janvier 1985 que Renault lance le Cherokee en France avec le moteur Turbo Diesel servi par la bo\u00eete manuelle \u00e0 cinq rapports. La version quatre portes \u00e9quip\u00e9e du m\u00eame moteur est disponible \u00e0 partir de juillet 1985. Le Cherokee re\u00e7oit le titre de 4&#215;4 de l&rsquo;ann\u00e9e 1986.<\/p>\n<p>En 1986, le moteur quatre cylindres essence est profond\u00e9ment revu avec l&rsquo;adoption de l&rsquo;injection permettant d&rsquo;am\u00e9liorer le confort d&rsquo;utilisation et de gagner 12 chevaux pour un total de 117. Une pr\u00e9paration baptis\u00e9e \u00ab\u00a0Off-Highway Vehicle\u00a0\u00bb est commercialis\u00e9e qui comprend des suspensions renforc\u00e9es, des pneus plus larges en 225\/75 R 15, des plaques de protection sous le ch\u00e2ssis, deux crochets, un rapport de pont de 4:10 pour faciliter la progression sur les pentes tr\u00e8s raides et dans la boue ainsi qu&rsquo;une garde au sol plus importante.<\/p>\n<p>Chrysler rach\u00e8te le groupe American Motors en 1987 mais Renault reste importateur et distributeur des Jeep pour plusieurs pays europ\u00e9ens dont la France, l&rsquo;Italie et l&rsquo;Espagne. Chrysler con\u00e7oit un bloc six cylindres en ligne de 4 litres \u00e0 injection d\u00e9veloppant 178 chevaux baptis\u00e9 \u00ab\u00a0Power-Tech Six\u00a0\u00bb. Il catapulte le Cherokee de 0 \u00e0 100 km\/h en pr\u00e8s de 9 secondes ce qui est remarquable pour un SUV. La capacit\u00e9 de remorquage atteint les 2,3 tonnes. La nouvelle bo\u00eete de vitesses automatique japonaise \u00e0 quatre rapports laisse au conducteur le choix entre deux programmes. En position \u00ab\u00a0Power\u00a0\u00bb, les vitesses passent \u00e0 un r\u00e9gime plus \u00e9lev\u00e9 et la bo\u00eete r\u00e9trograde plus vite. La souplesse et l&rsquo;\u00e9conomie sont privil\u00e9gi\u00e9es en position \u00ab\u00a0Comfort\u00a0\u00bb. La puissance du moteur quatre cylindres essence est port\u00e9e \u00e0 121 chevaux et la bo\u00eete de vitesses manuelle \u00e0 quatre rapports est abandonn\u00e9e pour la seule bo\u00eete \u00e0 cinq rapports. La carrosserie peut recevoir en option une peinture deux tons et les panneaux de garniture int\u00e9rieure des porti\u00e8res sont chang\u00e9s.<\/p>\n<p>Dans le courant de l&rsquo;ann\u00e9e est commercialis\u00e9e la finition Limited qui re\u00e7oit le meilleur en standard, ce qui comprend le moteur six cylindres, la bo\u00eete automatique \u00e0 quatre rapports, la transmission Selec Trac, les pare-chocs couleur caisse, les jantes et filets lat\u00e9raux dor\u00e9s, la sellerie cuir, la climatisation, les si\u00e8ges avant, vitres et r\u00e9troviseurs \u00e9lectriques, le r\u00e9gulateur de vitesse, le verrouillage centralis\u00e9 et l&rsquo;installation audio \u00e0 huit haut-parleurs. Le tissu des si\u00e8ges de la version Laredo et la d\u00e9coration ext\u00e9rieure de la version Chief sont revus.<\/p>\n<figure id=\"attachment_1644\" aria-describedby=\"caption-attachment-1644\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1644 \" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1988\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1988.jpg\" alt=\"\" width=\"315\" height=\"208\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1988.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1988-300x198.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1644\" class=\"wp-caption-text\">Cherokee Chief mod\u00e8le 1988 (Etats-Unis)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_1659\" aria-describedby=\"caption-attachment-1659\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1659 \" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"wago_1988\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/wago_1988.jpg\" alt=\"\" width=\"315\" height=\"208\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/wago_1988.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/wago_1988-300x198.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1659\" class=\"wp-caption-text\">Wagoneer mod\u00e8le 1988 (Etats-Unis)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Aux Etats-Unis est disponible en 1988 la version Limited deux portes et l&rsquo;impopulaire moteur Turbo Diesel sort du catalogue. Tous les mod\u00e8les re\u00e7oivent une nouvelle calandre \u00e0 huit ouvertures au lieu de dix et la version Laredo b\u00e9n\u00e9ficie d&rsquo;une nouvelle finition chrom\u00e9e et de protections lat\u00e9rales plus basses. Une version Sport deux portes avec des jantes en alliage et une d\u00e9coration sp\u00e9cifique met le Cherokee \u00e0 la port\u00e9e du plus grand nombre. En juin 1988, Renault commercialise la version Limited quatre portes avec le moteur six cylindres uniquement.<\/p>\n<p>L&rsquo;ABS fait son apparition en 1989 sur les versions six cylindres avec bo\u00eete automatique et transmission Selec Trac. Jeep innove en concevant un dispositif antiblocage qui, contrairement \u00e0 ce que propose la concurrence, fonctionne aussi bien en deux roues qu&rsquo;en quatre roues motrices. La direction assist\u00e9e n&rsquo;est plus une option sur les Cherokee d&rsquo;entr\u00e9e de gamme et tous les mod\u00e8les re\u00e7oivent un r\u00e9servoir de 75 litres au lieu de 51.<\/p>\n<figure id=\"attachment_1655\" aria-describedby=\"caption-attachment-1655\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1655 size-full\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher2p_1990\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher2p_1990.jpg\" alt=\"\" width=\"315\" height=\"176\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher2p_1990.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher2p_1990-300x167.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1655\" class=\"wp-caption-text\">Cherokee Chief mod\u00e8le 1990 (France)<\/figcaption><\/figure>\n<div class=\"mceTemp\">&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_1656\" aria-describedby=\"caption-attachment-1656\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1656 \" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher4p_1990\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher4p_1990.jpg\" alt=\"\" width=\"315\" height=\"176\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher4p_1990.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher4p_1990-300x167.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1656\" class=\"wp-caption-text\">Cherokee Limited mod\u00e8le 1990 (France)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>La s\u00e9curit\u00e9 \u00e0 bord est am\u00e9lior\u00e9e en 1990 avec le montage de ceintures trois points \u00e0 l&rsquo;arri\u00e8re. La version Limited re\u00e7oit une nouvelle console de toit comprenant une boussole, un thermom\u00e8tre ext\u00e9rieur et deux compartiments pour ranger une t\u00e9l\u00e9commande d&rsquo;ouverture de garage et une paire de lunettes. A partir de janvier 1990, Renault commercialise la version Limited avec la motorisation Turbo Diesel, la bo\u00eete m\u00e9canique et la transmission 4&#215;4 enclenchable. Pour 1991, la motorisation quatre cylindres essence re\u00e7oit une injection multi-points qui porte la puissance \u00e0 130 chevaux. Celle du moteur six cylindres atteint les 190 chevaux, ce qui permet au Cherokee de passer de 0 \u00e0 100 km\/h en moins de 9 secondes. La version Pioneer laisse la place \u00e0 une nouvelle finition Briarwood identifiable \u00e0 sa d\u00e9coration lat\u00e9rale en vinyle imitation bois. La version Sport deux portes est compl\u00e9t\u00e9e par un mod\u00e8le quatre portes. Le confort d&rsquo;utilisation progresse avec des cl\u00e9s sym\u00e9triques, les points de maintenance sous le capot surlign\u00e9s et en option un \u00e9clairage pour l&rsquo;acc\u00e8s \u00e0 bord.<\/p>\n<p>Pour l&rsquo;ann\u00e9e 1992, le Cherokee de base b\u00e9n\u00e9ficie de la moquette et la sellerie cuir est disponible en option sur la version Laredo quatre portes. Pour l&rsquo;exportation et \u00e0 destination des entreprises postales est d\u00e9velopp\u00e9e une version \u00e0 conduite \u00e0 droite.<\/p>\n<p>La gamme est simplifi\u00e9e en 1993. Sur les versions de base, Sport, Briarwood, Laredo et Limited sont conserv\u00e9es les seules finitions de base et Sport tandis qu&rsquo;est d\u00e9voil\u00e9e la nouvelle finition Country. La version Sport re\u00e7oit une peinture deux tons avec des bas de caisse noirs. La version Country comprend les \u00e9quipements de la d\u00e9funte version Limited et rev\u00eat une peinture champagne pour la caisse, les extensions d&rsquo;ailes et les pare-chocs. Les suspensions sont d\u00e9sormais en acier inoxydable afin de r\u00e9duire les co\u00fbts de maintenance.<\/p>\n<p>En France, le Cherokee n&rsquo;est plus livrable qu&rsquo;en quatre portes. Le contrat de distribution de Renault pour les Jeep est arriv\u00e9 \u00e0 \u00e9ch\u00e9ance fin 1992 et n&rsquo;a pas \u00e9t\u00e9 renouvel\u00e9. Sonauto reprend l&rsquo;importation pour la France au premier janvier 1993. A cette occasion, les prix baissent nettement et la gamme est r\u00e9duite avec la suppression du moteur six cylindres et de la version Limited. Le Cherokee est disponible soit en version Sp\u00e9ciale \u00e0 deux portes et motorisation quatre cylindres essence, soit en version Luxe \u00e0 quatre portes et motorisation quatre cylindres essence ou Turbo Diesel.<\/p>\n<figure id=\"attachment_1646\" aria-describedby=\"caption-attachment-1646\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1646 \" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1993\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993.jpg\" alt=\"\" width=\"315\" height=\"176\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993-300x167.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1646\" class=\"wp-caption-text\">Cherokee Sp\u00e9ciale mod\u00e8le 1994 (France)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_1645\" aria-describedby=\"caption-attachment-1645\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1645 \" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1993_2\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993_2.jpg\" alt=\"\" width=\"315\" height=\"176\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993_2.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1993_2-300x167.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><figcaption id=\"caption-attachment-1645\" class=\"wp-caption-text\">Cherokee Luxe mod\u00e8le 1994 (France)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Pour l&rsquo;ann\u00e9e 1994 sont install\u00e9es des barres de renfort dans les porti\u00e8res, le toit est renforc\u00e9, un troisi\u00e8me feu de stop est mont\u00e9 en haut du hayon et l&rsquo;air conditionn\u00e9 utilise un gaz r\u00e9frig\u00e9rant sans CFC. Une nouveau coloris argent est propos\u00e9e sur la version Country pour ceux qui ne trouvent pas le coloris champagne \u00e0 leur go\u00fbt et la finition de base est rebadg\u00e9e SE. A la fin de l&rsquo;ann\u00e9e 1994, le moteur Turbo Diesel Renault c\u00e8de sa place \u00e0 un moteur Turbo Diesel VM de 2,5 litres d\u00e9veloppant 117 chevaux. Des s\u00e9ries limit\u00e9es Jamboree ou Limited sont disponibles chez les concessionnaires Sonauto.<\/p>\n<p>En 1995, la motorisation quatre cylindres essence de la version SE peut aussi \u00eatre accoupl\u00e9e \u00e0 une bo\u00eete automatique \u00e0 trois rapports, celle \u00e0 quatre rapports restant r\u00e9serv\u00e9e aux versions Sport et Country avec motorisation six cylindres. Un airbag conducteur est disponible ainsi que de nouveaux coloris tels que Moss Green et Aqua Pearl. Chez Sonauto, le Cherokee Sp\u00e9ciale deux portes est disponible en motorisation essence ou Turbo Diesel. Les Cherokee quatre portes en version Luxe ou Country sont propos\u00e9s en motorisation Turbo Diesel uniquement.<\/p>\n<p>Les motorisations essence quatre et six cylindres sont retravaill\u00e9es pour 1996 dans le sens d&rsquo;une meilleure insonorisation et d&rsquo;une plus grande souplesse de fonctionnement. Le six cylindres est plus puissant \u00e0 bas r\u00e9gime pour offrir plus de r\u00e9pondant \u00e0 l&rsquo;acc\u00e9l\u00e9ration depuis l&rsquo;arr\u00eat et au remorquage sur des pentes raides. Le conducteur doit d\u00e9sormais enfoncer la p\u00e9dale de frein pour pouvoir sortir la bo\u00eete automatique de la position Park. Le syst\u00e8me \u00e9lectrique est renforc\u00e9 avec l&rsquo;adoption d&rsquo;une batterie et d&rsquo;un alternateur plus puissants. Le catalogue des peintures s&rsquo;enrichie des coloris Bright Jade et Stone White. A partir de juin 1996, Chrysler reprend le contr\u00f4le des op\u00e9rations \u00e0 la place de Sonauto par l&rsquo;interm\u00e9diaire d&rsquo;une filiale fran\u00e7aise. Le Cherokee Sp\u00e9ciale deux portes et le Cherokee Country quatre portes ne sont commercialis\u00e9s qu&rsquo;avec le moteur Turbo Diesel, \u00e0 l&rsquo;inverse du Cherokee Luxe quatre portes qui peut recevoir les deux motorisations.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1649 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1997\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997.jpg\" alt=\"\" width=\"315\" height=\"192\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997-300x182.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1647 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1997_2\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_2.jpg\" alt=\"\" width=\"315\" height=\"74\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_2.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_2-300x70.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1648 aligncenter\" style=\"border: 0px; margin-top: 0px; margin-bottom: 0px;\" title=\"cher_1997_3\" src=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_3.jpg\" alt=\"\" width=\"315\" height=\"105\" srcset=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_3.jpg 315w, https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1997_3-300x100.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;ann\u00e9e 1997 marque un profond remaniement du Cherokee. S&rsquo;appuyant sur les \u00e9tudes client\u00e8le, Chrysler travaille sur la qualit\u00e9 de fabrication, la r\u00e9duction du nombre de pi\u00e8ces, du bruit et des vibrations, la simplification du syst\u00e8me \u00e9lectrique et le rajeunissement de la carrosserie. Les contours des ailes avant et arri\u00e8re sont adoucis. La calandre, les moulures lat\u00e9rales, les feux arri\u00e8re et les pare-chocs sont discr\u00e8tement modifi\u00e9s. Les porti\u00e8res avant perdent leur petite glace. Les r\u00e9troviseurs sont agrandis. Les vitres peuvent en option \u00eatre encore plus teint\u00e9es. Le tout nouvel int\u00e9rieur de bien meilleure finition propose un tableau de bord offrant un airbag passager et une installation audio avec lecteurs de cassette et CD. Sont aussi enti\u00e8rement revus le syst\u00e8me de climatisation et les panneaux de garniture int\u00e9rieure des porti\u00e8res. La console centrale incorpore des porte-gobelets. Les miroirs et les interrupteurs des vitres \u00e9lectriques sont \u00e9clair\u00e9s. Un ordinateur de bord prend place dans la console de toit.<\/p>\n<p>Les niveaux de finition sont baptis\u00e9s SE, Sport, Classic et Limited, appellation qui fait un retour marqu\u00e9 apr\u00e8s quatre ann\u00e9es d&rsquo;absence. La finition Classic ajoute \u00e0 la finition Sport des pare-chocs et des moulures couleur caisse, des jantes en alliage, des barres de toit, la climatisation et les r\u00e9troviseurs \u00e9lectriques. Trois nouveaux coloris, Chili Pepper Red, Deep Amethyst et Emerald Green, arrivent au catalogue.<\/p>\n<p>En France, le Cherokee deux portes est disponible dans les finitions Sport et Jamboree offrant en plus la climatisation, mais uniquement avec le moteur Turbo Diesel. Le Cherokee quatre portes est propos\u00e9 dans les finitions Turbo Diesel Sport, Turbo Diesel Limited et six cylindres Limited. Cette derni\u00e8re variante est la seule \u00e0 offrir une sellerie cuir et une bo\u00eete automatique. Cette offre est reconduite pour l&rsquo;ann\u00e9e 1998.<\/p>\n<p>Quelques changements mineurs interviennent en 1999. La finition Sport re\u00e7oit des pare-chocs et une calandre couleur caisse. La version Limited peut recevoir en option des si\u00e8ges chauffants. Un nouveau dispositif anti-d\u00e9marrage est install\u00e9. Le fonctionnement des moteurs est am\u00e9lior\u00e9 gr\u00e2ce \u00e0 une \u00e9lectronique r\u00e9vis\u00e9e et un nouveau catalyseur.<\/p>\n<p>La gamme fran\u00e7aise se d\u00e9cline en six versions : Cherokee Sport avec moteur quatre cylindres essence en deux portes, Cherokee Sport ou Jamboree avec moteur Turbo Diesel en deux ou quatre portes et Cherokee Limited avec moteur six cylindres en quatre portes.<\/p>\n<p>Pour l&rsquo;ann\u00e9e 2000, le Cherokee re\u00e7oit du Grand Cherokee sa motorisation six cylindres r\u00e9vis\u00e9e l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. Ce moteur offre plus de souplesse et r\u00e9pond aux derni\u00e8res normes anti-pollution. Les versions SE et Sport peuvent recevoir de nouvelles bo\u00eetes manuelles \u00e0 cinq ou six rapports, la bo\u00eete automatique \u00e0 quatre rapports \u00e9quipant de s\u00e9rie les versions Classic et Limited. La finition Limited se distingue par le retour des chromes sur la calandre, les entourages des phares et le support de plaque arri\u00e8re ainsi que par des jantes en alliage argent\u00e9es. Le catalogue des peintures est remani\u00e9 avec l&rsquo;arriv\u00e9e entre autres des coloris Patriot Blue et Silverstone Pearls. En France, la finition Jamboree n&rsquo;est plus disponible sur le Cherokee deux portes.<\/p>\n<p>2001, la derni\u00e8re ann\u00e9e pour le Cherokee voit la disparition du moteur quatre cylindres essence, l&rsquo;arriv\u00e9e d&rsquo;ancrages pour les si\u00e8ges enfant et le coloris Steel Blue remplace le coloris Desert Sand.<\/p>\n<p>Pas d&rsquo;important changement non plus pour la France si ce n&rsquo;est l&rsquo;apparition des s\u00e9ries limit\u00e9es Wild Sport qui associe le moteur six cylindres et la carrosserie deux portes et 60th Anniversary Edition disponible avec les motorisations essence ou Turbo Diesel.<\/p>\n<p>La commercialisation du KJ est annonc\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ayant acquis la majorit\u00e9 du capital d&rsquo;American Motors \u00e0 la fin des ann\u00e9es 1970, Renault dirige l&rsquo;\u00e9tude d&rsquo;un tout nouveau mod\u00e8le moins volumineux et plus moderne. C&rsquo;est ainsi qu&rsquo;en 1984, au terme d&rsquo;un projet de 250 millions de Dollars, Jeep r\u00e9volutionne le segment des v\u00e9hicules \u00ab\u00a0sport utilitaire\u00a0\u00bb \u00e0 quatre roues motrices en pr\u00e9sentant la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":155,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-1522","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historique du Cherokee XJ - US Cars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historique du Cherokee XJ - US Cars\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Ayant acquis la majorit\u00e9 du capital d&rsquo;American Motors \u00e0 la fin des ann\u00e9es 1970, Renault dirige l&rsquo;\u00e9tude d&rsquo;un tout nouveau mod\u00e8le moins volumineux et plus moderne. C&rsquo;est ainsi qu&rsquo;en 1984, au terme d&rsquo;un projet de 250 millions de Dollars, Jeep r\u00e9volutionne le segment des v\u00e9hicules \u00ab\u00a0sport utilitaire\u00a0\u00bb \u00e0 quatre roues motrices en pr\u00e9sentant la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/\" \/>\n<meta property=\"og:site_name\" content=\"US Cars\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscars.france\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-07T17:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@uscarsfrance\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/\",\"url\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/\",\"name\":\"Historique du Cherokee XJ - US Cars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/cher_1984.jpg\",\"datePublished\":\"2012-12-01T23:22:37+00:00\",\"dateModified\":\"2025-06-07T17:04:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/cher_1984.jpg\",\"contentUrl\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/cher_1984.jpg\",\"width\":\"320\",\"height\":\"224\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/historique-cherokee-xj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeep\",\"item\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jeep Cherokee de 1984 \u00e0 2013\",\"item\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/jeep\\\/cherokee\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Historique du Cherokee XJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/\",\"name\":\"US Cars\",\"description\":\"La passion des voitures am\u00e9ricaines\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#organization\",\"name\":\"US Cars\",\"url\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cropped-uscars_carre_512x512.png\",\"contentUrl\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/cropped-uscars_carre_512x512.png\",\"width\":512,\"height\":512,\"caption\":\"US Cars\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uscars.biz\\\/uscars.wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/uscars.france\",\"https:\\\/\\\/x.com\\\/uscarsfrance\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/uscarsdotbiz\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historique du Cherokee XJ - US Cars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/","og_locale":"fr_FR","og_type":"article","og_title":"Historique du Cherokee XJ - US Cars","og_description":"&nbsp; Ayant acquis la majorit\u00e9 du capital d&rsquo;American Motors \u00e0 la fin des ann\u00e9es 1970, Renault dirige l&rsquo;\u00e9tude d&rsquo;un tout nouveau mod\u00e8le moins volumineux et plus moderne. C&rsquo;est ainsi qu&rsquo;en 1984, au terme d&rsquo;un projet de 250 millions de Dollars, Jeep r\u00e9volutionne le segment des v\u00e9hicules \u00ab\u00a0sport utilitaire\u00a0\u00bb \u00e0 quatre roues motrices en pr\u00e9sentant la [&hellip;]","og_url":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/","og_site_name":"US Cars","article_publisher":"https:\/\/www.facebook.com\/uscars.france","article_modified_time":"2025-06-07T17:04:18+00:00","og_image":[{"width":320,"height":224,"url":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@uscarsfrance","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/","url":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/","name":"Historique du Cherokee XJ - US Cars","isPartOf":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/#primaryimage"},"image":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg","datePublished":"2012-12-01T23:22:37+00:00","dateModified":"2025-06-07T17:04:18+00:00","breadcrumb":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/#primaryimage","url":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg","contentUrl":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2012\/12\/cher_1984.jpg","width":"320","height":"224"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/historique-cherokee-xj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.uscars.biz\/uscars.wordpress\/"},{"@type":"ListItem","position":2,"name":"Jeep","item":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/"},{"@type":"ListItem","position":3,"name":"Jeep Cherokee de 1984 \u00e0 2013","item":"https:\/\/www.uscars.biz\/uscars.wordpress\/jeep\/cherokee\/"},{"@type":"ListItem","position":4,"name":"Historique du Cherokee XJ"}]},{"@type":"WebSite","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#website","url":"https:\/\/www.uscars.biz\/uscars.wordpress\/","name":"US Cars","description":"La passion des voitures am\u00e9ricaines","publisher":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uscars.biz\/uscars.wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#organization","name":"US Cars","url":"https:\/\/www.uscars.biz\/uscars.wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2016\/09\/cropped-uscars_carre_512x512.png","contentUrl":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-content\/uploads\/2016\/09\/cropped-uscars_carre_512x512.png","width":512,"height":512,"caption":"US Cars"},"image":{"@id":"https:\/\/www.uscars.biz\/uscars.wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uscars.france","https:\/\/x.com\/uscarsfrance","https:\/\/www.youtube.com\/user\/uscarsdotbiz"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P2RQDg-oy","_links":{"self":[{"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/pages\/1522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/comments?post=1522"}],"version-history":[{"count":56,"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/pages\/1522\/revisions"}],"predecessor-version":[{"id":1022136,"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/pages\/1522\/revisions\/1022136"}],"up":[{"embeddable":true,"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/pages\/155"}],"wp:attachment":[{"href":"https:\/\/www.uscars.biz\/uscars.wordpress\/wp-json\/wp\/v2\/media?parent=1522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}